{"id":17,"count":2,"description":"","link":"https:\/\/pedonetomeo.archi\/en\/tag\/vision\/","name":"vision","slug":"vision","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>vision Archivi - Pedone Tomeo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pedonetomeo.archi\/en\/tag\/vision\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"vision Archivi - Pedone Tomeo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pedonetomeo.archi\/en\/tag\/vision\/\" \/>\n<meta property=\"og:site_name\" content=\"Pedone Tomeo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/pedonetomeo.archi\/en\/tag\/vision\/\",\"url\":\"https:\/\/pedonetomeo.archi\/en\/tag\/vision\/\",\"name\":\"vision Archivi - Pedone Tomeo\",\"isPartOf\":{\"@id\":\"https:\/\/pedonetomeo.archi\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/pedonetomeo.archi\/en\/tag\/vision\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pedonetomeo.archi\/en\/tag\/vision\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/pedonetomeo.archi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"vision\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pedonetomeo.archi\/#website\",\"url\":\"https:\/\/pedonetomeo.archi\/\",\"name\":\"Pedone Tomeo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pedonetomeo.archi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"vision Archivi - Pedone Tomeo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pedonetomeo.archi\/en\/tag\/vision\/","og_locale":"en_US","og_type":"article","og_title":"vision Archivi - Pedone Tomeo","og_url":"https:\/\/pedonetomeo.archi\/en\/tag\/vision\/","og_site_name":"Pedone Tomeo","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/pedonetomeo.archi\/en\/tag\/vision\/","url":"https:\/\/pedonetomeo.archi\/en\/tag\/vision\/","name":"vision Archivi - Pedone Tomeo","isPartOf":{"@id":"https:\/\/pedonetomeo.archi\/#website"},"breadcrumb":{"@id":"https:\/\/pedonetomeo.archi\/en\/tag\/vision\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/pedonetomeo.archi\/en\/tag\/vision\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pedonetomeo.archi\/"},{"@type":"ListItem","position":2,"name":"vision"}]},{"@type":"WebSite","@id":"https:\/\/pedonetomeo.archi\/#website","url":"https:\/\/pedonetomeo.archi\/","name":"Pedone Tomeo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pedonetomeo.archi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/tags\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/posts?tags=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}