{"id":1862,"date":"2023-03-17T13:15:19","date_gmt":"2023-03-17T12:15:19","guid":{"rendered":"https:\/\/pedonetomeo.archi\/?p=1862"},"modified":"2023-03-17T16:21:09","modified_gmt":"2023-03-17T15:21:09","slug":"nuovo-progetto-store-melluso-in-franciacorta-village","status":"publish","type":"post","link":"https:\/\/pedonetomeo.archi\/en\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/","title":{"rendered":"Nuovo progetto: Store Melluso in Franciacorta Village"},"content":{"rendered":"<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xdj266r x126k92a\">\n<div dir=\"auto\">Ecco alcune immagini del nostro nuovo progetto, realizzato per lo ????? ??????? in <a class=\"x1i10hfl xjbqb8w x6umtig x1b1mbwd xaqea5y xav7gou x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xt0b8zv x1qq9wsj xo1l8bm\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/franciacortavillage\/?__cft__[0]=AZXI65fz217CcR62ZSNBiGp7kenxK44m2lFB61WvOH5rYD68NHkaU3fmPx12-KeuKWDwXvrmTTQBkgzIr6pGkxYsWntYZww8zY9QKYkz_at_tCZ10YLf4q0tqgsjc9UXbYEDz_7qiK3wAlroRpL_lbYHPvCIBFSA-YSO2IvthcZRObtQGjOk0sejU7vTeBf_bS0&amp;__tn__=kK-R\"><span class=\"xt0psk2\">Franciacorta Village<\/span><\/a>.<\/div>\n<div dir=\"auto\">Un concept innovativo, moderno, che nasce con l&#8217;obiettivo di ottimizzare gli spazi e garantire la massima visibilit\u00e0 ai prodotti, grazie ad un design minimal e al tempo stesso funzionale, che pone l\u2019accento su silhouette morbide e colori caldi.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Driver del progetto \u00e8 l\u2019ecosostenibilit\u00e0, intesa come atteggiamento culturale e di rimando estetico. Per la realizzazione del punto vendita \u00e8 stato utilizzato il legno di rovere trattato al naturale e sistemi di illuminazione a basso consumo energetico. Non mancano, all\u2019interno della struttura, spazi verdi. Tutto ci\u00f2 restituisce all\u2019utente una forte sensazione di \u201chome feeling\u201d.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">\n<p>Dalla collaborazione di oltre quindici anni tra il nostro studio e Melluso, sono nati oltre sessanta punti vendita in Italia e all\u2019estero, caratterizzati da una profonda attenzione ai temi dell\u2019eleganza italiana ed oggi anche dell&#8217;ecosostenibilit\u00e0.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 100%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-1862 gallery-columns-1 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Store Melluso\" data-caption=\"\" href='https:\/\/pedonetomeo.archi\/en\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/attachment\/00\/'><img decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/00.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/00-16x12.jpg 16w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/00-200x150.jpg 200w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/00-300x225.jpg 300w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/00-400x300.jpg 400w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/00-600x450.jpg 600w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/00-768x576.jpg 768w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/00-800x600.jpg 800w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/00-1024x768.jpg 1024w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/00-1200x900.jpg 1200w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/00-1536x1152.jpg 1536w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/00.jpg 1600w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Store Melluso\" data-caption=\"\" href='https:\/\/pedonetomeo.archi\/en\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/01_render\/'><img decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/01_render-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/01_render-16x9.jpg 16w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/01_render-200x113.jpg 200w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/01_render-300x169.jpg 300w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/01_render-400x225.jpg 400w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/01_render-600x338.jpg 600w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/01_render-768x432.jpg 768w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/01_render-800x450.jpg 800w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/01_render-1024x576.jpg 1024w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/01_render-1200x675.jpg 1200w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/01_render-1536x864.jpg 1536w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/01_render-scaled.jpg 2560w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Render Store Melluso\" data-caption=\"\" href='https:\/\/pedonetomeo.archi\/en\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/03-elenco-render\/'><img decoding=\"async\" width=\"1294\" height=\"901\" src=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/03.-elenco-render.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/03.-elenco-render-16x12.jpg 16w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/03.-elenco-render-200x139.jpg 200w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/03.-elenco-render-300x209.jpg 300w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/03.-elenco-render-400x279.jpg 400w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/03.-elenco-render-600x418.jpg 600w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/03.-elenco-render-768x535.jpg 768w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/03.-elenco-render-800x557.jpg 800w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/03.-elenco-render-1024x713.jpg 1024w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/03.-elenco-render-1200x836.jpg 1200w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/03.-elenco-render.jpg 1294w\" sizes=\"(max-width: 1294px) 100vw, 1294px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Store Melluso\" data-caption=\"\" href='https:\/\/pedonetomeo.archi\/en\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/attachment\/04\/'><img decoding=\"async\" width=\"1132\" height=\"1568\" src=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/04..jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/04.-9x12.jpg 9w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/04.-200x277.jpg 200w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/04.-217x300.jpg 217w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/04.-400x554.jpg 400w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/04.-600x831.jpg 600w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/04.-739x1024.jpg 739w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/04.-768x1064.jpg 768w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/04.-800x1108.jpg 800w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/04.-1109x1536.jpg 1109w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/04..jpg 1132w\" sizes=\"(max-width: 1132px) 100vw, 1132px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Foto negozio Store Melluso\" data-caption=\"\" href='https:\/\/pedonetomeo.archi\/en\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/05-foto-negozio_-quadrata\/'><img decoding=\"async\" width=\"904\" height=\"829\" src=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/05.-foto-negozio_-quadrata.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/05.-foto-negozio_-quadrata-13x12.jpg 13w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/05.-foto-negozio_-quadrata-200x183.jpg 200w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/05.-foto-negozio_-quadrata-300x275.jpg 300w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/05.-foto-negozio_-quadrata-400x367.jpg 400w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/05.-foto-negozio_-quadrata-600x550.jpg 600w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/05.-foto-negozio_-quadrata-768x704.jpg 768w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/05.-foto-negozio_-quadrata-800x734.jpg 800w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/05.-foto-negozio_-quadrata.jpg 904w\" sizes=\"(max-width: 904px) 100vw, 904px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ecco alcune immagini del nostro nuovo progetto, realizzato per lo [&hellip;]<\/p>","protected":false},"author":1,"featured_media":1863,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nuovo progetto: Store Melluso in Franciacorta Village - Pedone Tomeo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pedonetomeo.archi\/en\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuovo progetto: Store Melluso in Franciacorta Village - Pedone Tomeo\" \/>\n<meta property=\"og:description\" content=\"Ecco alcune immagini del nostro nuovo progetto, realizzato per lo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pedonetomeo.archi\/en\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/\" \/>\n<meta property=\"og:site_name\" content=\"Pedone Tomeo\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-17T12:15:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-17T15:21:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/Progetto-senza-titolo-6.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"adm_PedTomeo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"adm_PedTomeo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/\",\"url\":\"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/\",\"name\":\"Nuovo progetto: Store Melluso in Franciacorta Village - Pedone Tomeo\",\"isPartOf\":{\"@id\":\"https:\/\/pedonetomeo.archi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/Progetto-senza-titolo-6.png\",\"datePublished\":\"2023-03-17T12:15:19+00:00\",\"dateModified\":\"2023-03-17T15:21:09+00:00\",\"author\":{\"@id\":\"https:\/\/pedonetomeo.archi\/#\/schema\/person\/5bc185703efff23844de9796b75944db\"},\"breadcrumb\":{\"@id\":\"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/#primaryimage\",\"url\":\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/Progetto-senza-titolo-6.png\",\"contentUrl\":\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/Progetto-senza-titolo-6.png\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/pedonetomeo.archi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuovo progetto: Store Melluso in Franciacorta Village\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pedonetomeo.archi\/#website\",\"url\":\"https:\/\/pedonetomeo.archi\/\",\"name\":\"Pedone Tomeo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pedonetomeo.archi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/pedonetomeo.archi\/#\/schema\/person\/5bc185703efff23844de9796b75944db\",\"name\":\"adm_PedTomeo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/pedonetomeo.archi\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f6e14970b1ce586032424e4d08abefdd253cec0fb62cc49d5591f0caae1dcd1b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f6e14970b1ce586032424e4d08abefdd253cec0fb62cc49d5591f0caae1dcd1b?s=96&d=mm&r=g\",\"caption\":\"adm_PedTomeo\"},\"sameAs\":[\"https:\/\/pedonetomeo.archi\"],\"url\":\"https:\/\/pedonetomeo.archi\/en\/author\/adm_pedtomeo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuovo progetto: Store Melluso in Franciacorta Village - Pedone Tomeo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pedonetomeo.archi\/en\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/","og_locale":"en_US","og_type":"article","og_title":"Nuovo progetto: Store Melluso in Franciacorta Village - Pedone Tomeo","og_description":"Ecco alcune immagini del nostro nuovo progetto, realizzato per lo [&hellip;]","og_url":"https:\/\/pedonetomeo.archi\/en\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/","og_site_name":"Pedone Tomeo","article_published_time":"2023-03-17T12:15:19+00:00","article_modified_time":"2023-03-17T15:21:09+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/Progetto-senza-titolo-6.png","type":"image\/png"}],"author":"adm_PedTomeo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"adm_PedTomeo","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/","url":"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/","name":"Nuovo progetto: Store Melluso in Franciacorta Village - Pedone Tomeo","isPartOf":{"@id":"https:\/\/pedonetomeo.archi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/#primaryimage"},"image":{"@id":"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/#primaryimage"},"thumbnailUrl":"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/Progetto-senza-titolo-6.png","datePublished":"2023-03-17T12:15:19+00:00","dateModified":"2023-03-17T15:21:09+00:00","author":{"@id":"https:\/\/pedonetomeo.archi\/#\/schema\/person\/5bc185703efff23844de9796b75944db"},"breadcrumb":{"@id":"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/#primaryimage","url":"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/Progetto-senza-titolo-6.png","contentUrl":"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2023\/03\/Progetto-senza-titolo-6.png","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/pedonetomeo.archi\/2023\/03\/17\/nuovo-progetto-store-melluso-in-franciacorta-village\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pedonetomeo.archi\/"},{"@type":"ListItem","position":2,"name":"Nuovo progetto: Store Melluso in Franciacorta Village"}]},{"@type":"WebSite","@id":"https:\/\/pedonetomeo.archi\/#website","url":"https:\/\/pedonetomeo.archi\/","name":"Pedone Tomeo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pedonetomeo.archi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/pedonetomeo.archi\/#\/schema\/person\/5bc185703efff23844de9796b75944db","name":"adm_PedTomeo","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pedonetomeo.archi\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f6e14970b1ce586032424e4d08abefdd253cec0fb62cc49d5591f0caae1dcd1b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6e14970b1ce586032424e4d08abefdd253cec0fb62cc49d5591f0caae1dcd1b?s=96&d=mm&r=g","caption":"adm_PedTomeo"},"sameAs":["https:\/\/pedonetomeo.archi"],"url":"https:\/\/pedonetomeo.archi\/en\/author\/adm_pedtomeo\/"}]}},"_links":{"self":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/posts\/1862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/comments?post=1862"}],"version-history":[{"count":4,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/posts\/1862\/revisions"}],"predecessor-version":[{"id":1878,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/posts\/1862\/revisions\/1878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/media\/1863"}],"wp:attachment":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/media?parent=1862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/categories?post=1862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/tags?post=1862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}