{"id":1791,"date":"2022-05-09T16:26:13","date_gmt":"2022-05-09T14:26:13","guid":{"rendered":"https:\/\/pedonetomeo.archi\/?p=1791"},"modified":"2022-05-09T18:24:29","modified_gmt":"2022-05-09T16:24:29","slug":"lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022","status":"publish","type":"post","link":"https:\/\/pedonetomeo.archi\/en\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/","title":{"rendered":"Lo Studio Pedone&#038;Tomeo riconosciuto tra le Top Company alla Borsa Mediterranea della Formazione e del Lavoro 2022"},"content":{"rendered":"<div>\n<p class=\"xmprfx_MsoNormal\">Il nostro Studio ha ricevuto il premio come <strong>Top Company<\/strong> nell&#8217;ambito della 3^ edizione della <strong><a href=\"https:\/\/www.borsaformazionelavoro.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Borsa Mediterranea della Formazione e del Lavoro<\/a>,\u00a0<\/strong>tenutasi dal 4 al 5 maggio presso la Stazione Marittima di Salerno.<\/p>\n<\/div>\n<div>\n<p class=\"xmprfx_MsoNormal\">Il prestigioso riconoscimento \u00e8 stato ritirato dagli architetti e founder <strong>Alessandra Pedone<\/strong> and <strong>Carlo Tomeo<\/strong> in occasione della cerimonia di premiazione delle aziende virtuose alla Stazione Marittima.<\/p>\n<\/div>\n<div>\n<p class=\"xmprfx_MsoNormal\">Ecco le motivazioni: \u201c<em>Per l\u2019attenzione alle giovani generazioni e la promozione della cultura architettonica, valori manifestati con la partecipazione al progetto PON \u201cOrientare per crescere\u201d con gli studenti del Liceo Scientifico Medi di Battipaglia e il supporto a eventi, iniziative e contest di grande impatto per i giovani e il territorio<\/em>\u201d.<\/p>\n<\/div>\n<div>\n<p class=\"xmprfx_MsoNormal\">Grazie agli organizzatori della <strong>Borsa Mediterranea della Formazione e del Lavoro<\/strong> e al CTS del <strong>Centro Studi Super Sud<\/strong> per averci selezionato tra le <strong>Top Company<\/strong> del territorio. Un ringraziamento alla dirigente del Liceo Medi dott.ssa <strong>Roberta Talamo<\/strong>, alla professoressa <strong>Maria Rosaria Galluzzi<\/strong> e alla professoressa <strong>Marcella Solimeo<\/strong>.<\/p>\n<\/div>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-1791 gallery-columns-2 gallery-size-large'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"2 Premio BMFL 2022\" data-caption=\"\" href='https:\/\/pedonetomeo.archi\/en\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/2-premio-bmfl-2022\/'><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/2-Premio-BMFL-2022-1024x683.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/2-Premio-BMFL-2022-16x12.jpeg 16w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/2-Premio-BMFL-2022-200x133.jpeg 200w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/2-Premio-BMFL-2022-300x200.jpeg 300w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/2-Premio-BMFL-2022-400x267.jpeg 400w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/2-Premio-BMFL-2022-600x400.jpeg 600w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/2-Premio-BMFL-2022-768x512.jpeg 768w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/2-Premio-BMFL-2022-800x533.jpeg 800w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/2-Premio-BMFL-2022-1024x683.jpeg 1024w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/2-Premio-BMFL-2022-1200x800.jpeg 1200w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/2-Premio-BMFL-2022.jpeg 1374w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"3 Premio BMFL 2022\" data-caption=\"\" href='https:\/\/pedonetomeo.archi\/en\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/3-premio-bmfl-2022\/'><img decoding=\"async\" width=\"809\" height=\"1024\" src=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/3-Premio-BMFL-2022-809x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/3-Premio-BMFL-2022-9x12.jpeg 9w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/3-Premio-BMFL-2022-200x253.jpeg 200w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/3-Premio-BMFL-2022-237x300.jpeg 237w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/3-Premio-BMFL-2022-400x506.jpeg 400w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/3-Premio-BMFL-2022-600x759.jpeg 600w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/3-Premio-BMFL-2022-768x972.jpeg 768w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/3-Premio-BMFL-2022-800x1012.jpeg 800w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/3-Premio-BMFL-2022-809x1024.jpeg 809w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/3-Premio-BMFL-2022.jpeg 1066w\" sizes=\"(max-width: 809px) 100vw, 809px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Premio BMFL 2022 1\" data-caption=\"\" href='https:\/\/pedonetomeo.archi\/en\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/premio-bmfl-2022-1\/'><img decoding=\"async\" width=\"659\" height=\"1024\" src=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-1-659x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-1-8x12.jpg 8w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-1-193x300.jpg 193w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-1-200x311.jpg 200w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-1-400x621.jpg 400w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-1-600x932.jpg 600w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-1-659x1024.jpg 659w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-1-768x1193.jpg 768w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-1-800x1242.jpg 800w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-1-989x1536.jpg 989w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-1.jpg 993w\" sizes=\"(max-width: 659px) 100vw, 659px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Premio BMFL 2022\" data-caption=\"\" href='https:\/\/pedonetomeo.archi\/en\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/premio-bmfl-2022\/'><img decoding=\"async\" width=\"1024\" height=\"699\" src=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-1024x699.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-16x12.jpg 16w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-200x136.jpg 200w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-300x205.jpg 300w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-400x273.jpg 400w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-600x409.jpg 600w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-768x524.jpg 768w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-800x546.jpg 800w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-1024x699.jpg 1024w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022-1200x819.jpg 1200w, https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/Premio-BMFL-2022.jpg 1319w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Il nostro Studio ha ricevuto il premio come Top Company [&hellip;]<\/p>","protected":false},"author":1,"featured_media":1792,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[81,90,89,82,86,88,87],"class_list":["post-1791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-architetti","tag-bmfl-2022","tag-borsa-mediterranea-formazione-lavoro","tag-pedone-tomeo","tag-premio","tag-terza-edizione","tag-top-company"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lo Studio Pedone&amp;Tomeo riconosciuto tra le Top Company alla Borsa Mediterranea della Formazione e del Lavoro 2022 - Pedone Tomeo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pedonetomeo.archi\/en\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo Studio Pedone&amp;Tomeo riconosciuto tra le Top Company alla Borsa Mediterranea della Formazione e del Lavoro 2022 - Pedone Tomeo\" \/>\n<meta property=\"og:description\" content=\"Il nostro Studio ha ricevuto il premio come Top Company [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pedonetomeo.archi\/en\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Pedone Tomeo\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-09T14:26:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-09T16:24:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/NEWS_BORSA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adm_PedTomeo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"adm_PedTomeo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/\",\"url\":\"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/\",\"name\":\"Lo Studio Pedone&Tomeo riconosciuto tra le Top Company alla Borsa Mediterranea della Formazione e del Lavoro 2022 - Pedone Tomeo\",\"isPartOf\":{\"@id\":\"https:\/\/pedonetomeo.archi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/NEWS_BORSA.jpg\",\"datePublished\":\"2022-05-09T14:26:13+00:00\",\"dateModified\":\"2022-05-09T16:24:29+00:00\",\"author\":{\"@id\":\"https:\/\/pedonetomeo.archi\/#\/schema\/person\/5bc185703efff23844de9796b75944db\"},\"breadcrumb\":{\"@id\":\"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/#primaryimage\",\"url\":\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/NEWS_BORSA.jpg\",\"contentUrl\":\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/NEWS_BORSA.jpg\",\"width\":800,\"height\":533,\"caption\":\"Premio Top Company Pedone Tomeo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/pedonetomeo.archi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo Studio Pedone&#038;Tomeo riconosciuto tra le Top Company alla Borsa Mediterranea della Formazione e del Lavoro 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pedonetomeo.archi\/#website\",\"url\":\"https:\/\/pedonetomeo.archi\/\",\"name\":\"Pedone Tomeo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pedonetomeo.archi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/pedonetomeo.archi\/#\/schema\/person\/5bc185703efff23844de9796b75944db\",\"name\":\"adm_PedTomeo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/pedonetomeo.archi\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f6e14970b1ce586032424e4d08abefdd253cec0fb62cc49d5591f0caae1dcd1b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f6e14970b1ce586032424e4d08abefdd253cec0fb62cc49d5591f0caae1dcd1b?s=96&d=mm&r=g\",\"caption\":\"adm_PedTomeo\"},\"sameAs\":[\"https:\/\/pedonetomeo.archi\"],\"url\":\"https:\/\/pedonetomeo.archi\/en\/author\/adm_pedtomeo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo Studio Pedone&Tomeo riconosciuto tra le Top Company alla Borsa Mediterranea della Formazione e del Lavoro 2022 - Pedone Tomeo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pedonetomeo.archi\/en\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/","og_locale":"en_US","og_type":"article","og_title":"Lo Studio Pedone&Tomeo riconosciuto tra le Top Company alla Borsa Mediterranea della Formazione e del Lavoro 2022 - Pedone Tomeo","og_description":"Il nostro Studio ha ricevuto il premio come Top Company [&hellip;]","og_url":"https:\/\/pedonetomeo.archi\/en\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/","og_site_name":"Pedone Tomeo","article_published_time":"2022-05-09T14:26:13+00:00","article_modified_time":"2022-05-09T16:24:29+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/NEWS_BORSA.jpg","type":"image\/jpeg"}],"author":"adm_PedTomeo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"adm_PedTomeo","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/","url":"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/","name":"Lo Studio Pedone&Tomeo riconosciuto tra le Top Company alla Borsa Mediterranea della Formazione e del Lavoro 2022 - Pedone Tomeo","isPartOf":{"@id":"https:\/\/pedonetomeo.archi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/#primaryimage"},"image":{"@id":"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/NEWS_BORSA.jpg","datePublished":"2022-05-09T14:26:13+00:00","dateModified":"2022-05-09T16:24:29+00:00","author":{"@id":"https:\/\/pedonetomeo.archi\/#\/schema\/person\/5bc185703efff23844de9796b75944db"},"breadcrumb":{"@id":"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/#primaryimage","url":"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/NEWS_BORSA.jpg","contentUrl":"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2022\/05\/NEWS_BORSA.jpg","width":800,"height":533,"caption":"Premio Top Company Pedone Tomeo"},{"@type":"BreadcrumbList","@id":"https:\/\/pedonetomeo.archi\/2022\/05\/09\/lo-studio-pedonetomeo-riconosciuto-tra-le-top-company-alla-borsa-mediterranea-della-formazione-e-del-lavoro-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pedonetomeo.archi\/"},{"@type":"ListItem","position":2,"name":"Lo Studio Pedone&#038;Tomeo riconosciuto tra le Top Company alla Borsa Mediterranea della Formazione e del Lavoro 2022"}]},{"@type":"WebSite","@id":"https:\/\/pedonetomeo.archi\/#website","url":"https:\/\/pedonetomeo.archi\/","name":"Pedone Tomeo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pedonetomeo.archi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/pedonetomeo.archi\/#\/schema\/person\/5bc185703efff23844de9796b75944db","name":"adm_PedTomeo","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pedonetomeo.archi\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f6e14970b1ce586032424e4d08abefdd253cec0fb62cc49d5591f0caae1dcd1b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6e14970b1ce586032424e4d08abefdd253cec0fb62cc49d5591f0caae1dcd1b?s=96&d=mm&r=g","caption":"adm_PedTomeo"},"sameAs":["https:\/\/pedonetomeo.archi"],"url":"https:\/\/pedonetomeo.archi\/en\/author\/adm_pedtomeo\/"}]}},"_links":{"self":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/posts\/1791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/comments?post=1791"}],"version-history":[{"count":2,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/posts\/1791\/revisions"}],"predecessor-version":[{"id":1798,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/posts\/1791\/revisions\/1798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/media\/1792"}],"wp:attachment":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/media?parent=1791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/categories?post=1791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/tags?post=1791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}