{"id":2076,"date":"2025-07-02T10:09:48","date_gmt":"2025-07-02T08:09:48","guid":{"rendered":"https:\/\/pedonetomeo.archi\/?post_type=avada_portfolio&#038;p=2076"},"modified":"2025-07-02T10:23:57","modified_gmt":"2025-07-02T08:23:57","slug":"casa-a-san-cesareo","status":"publish","type":"avada_portfolio","link":"https:\/\/pedonetomeo.archi\/en\/portfolio-items\/casa-a-san-cesareo\/","title":{"rendered":"Casa A. San Cesareo"},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong>Location:<\/strong> San Cesareo, Roma<\/p>\n<p style=\"font-weight: 400;\"><strong>Status:<\/strong> unbuilt<\/p>\n<p style=\"font-weight: 400;\"><strong>Size<\/strong>\u00a0: 320 sqm<\/p>\n<p style=\"font-weight: 400;\"><strong>Client:<\/strong> private house<\/p>\n<p style=\"font-weight: 400;\">Struttura portante in legno a telaio con ampie vetrate. La casa, di piccole dimensioni, \u00e8 organizzata a doppia altezza in modo da dilatare la percezione degli spazi interni. Cubo vetrato in modo da avere un forte rapporto interno\/esterno. Disposta su due piani, con piccola piscina nel giardino e completata nelle pareti esterne e perimetrali del giardino in mattoncini di \u201cromana\u201d memoria.<\/p>","protected":false},"excerpt":{"rendered":"<p>Location: San Cesareo, Roma Status: unbuilt Size\u00a0: 320 sqm Client: [&hellip;]<\/p>","protected":false},"author":1,"featured_media":2077,"menu_order":0,"template":"","format":"standard","meta":{"footnotes":""},"portfolio_category":[7],"portfolio_skills":[],"portfolio_tags":[],"class_list":["post-2076","avada_portfolio","type-avada_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-architecture"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Casa A. San Cesareo - Pedone Tomeo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pedonetomeo.archi\/en\/portfolio-items\/casa-a-san-cesareo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa A. San Cesareo - Pedone Tomeo\" \/>\n<meta property=\"og:description\" content=\"Location: San Cesareo, Roma Status: unbuilt Size\u00a0: 320 sqm Client: [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pedonetomeo.archi\/en\/portfolio-items\/casa-a-san-cesareo\/\" \/>\n<meta property=\"og:site_name\" content=\"Pedone Tomeo\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-02T08:23:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2025\/07\/foto-di-riferimento-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/\",\"url\":\"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/\",\"name\":\"Casa A. San Cesareo - Pedone Tomeo\",\"isPartOf\":{\"@id\":\"https:\/\/pedonetomeo.archi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2025\/07\/foto-di-riferimento-1-scaled.jpg\",\"datePublished\":\"2025-07-02T08:09:48+00:00\",\"dateModified\":\"2025-07-02T08:23:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/#primaryimage\",\"url\":\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2025\/07\/foto-di-riferimento-1-scaled.jpg\",\"contentUrl\":\"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2025\/07\/foto-di-riferimento-1-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/pedonetomeo.archi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\/\/pedonetomeo.archi\/portfolio-items\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Casa A. San Cesareo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pedonetomeo.archi\/#website\",\"url\":\"https:\/\/pedonetomeo.archi\/\",\"name\":\"Pedone Tomeo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pedonetomeo.archi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casa A. San Cesareo - Pedone Tomeo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pedonetomeo.archi\/en\/portfolio-items\/casa-a-san-cesareo\/","og_locale":"en_US","og_type":"article","og_title":"Casa A. San Cesareo - Pedone Tomeo","og_description":"Location: San Cesareo, Roma Status: unbuilt Size\u00a0: 320 sqm Client: [&hellip;]","og_url":"https:\/\/pedonetomeo.archi\/en\/portfolio-items\/casa-a-san-cesareo\/","og_site_name":"Pedone Tomeo","article_modified_time":"2025-07-02T08:23:57+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2025\/07\/foto-di-riferimento-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/","url":"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/","name":"Casa A. San Cesareo - Pedone Tomeo","isPartOf":{"@id":"https:\/\/pedonetomeo.archi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/#primaryimage"},"image":{"@id":"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/#primaryimage"},"thumbnailUrl":"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2025\/07\/foto-di-riferimento-1-scaled.jpg","datePublished":"2025-07-02T08:09:48+00:00","dateModified":"2025-07-02T08:23:57+00:00","breadcrumb":{"@id":"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/#primaryimage","url":"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2025\/07\/foto-di-riferimento-1-scaled.jpg","contentUrl":"https:\/\/pedonetomeo.archi\/wp-content\/uploads\/2025\/07\/foto-di-riferimento-1-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/pedonetomeo.archi\/portfolio-items\/casa-a-san-cesareo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pedonetomeo.archi\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/pedonetomeo.archi\/portfolio-items\/"},{"@type":"ListItem","position":3,"name":"Casa A. San Cesareo"}]},{"@type":"WebSite","@id":"https:\/\/pedonetomeo.archi\/#website","url":"https:\/\/pedonetomeo.archi\/","name":"Pedone Tomeo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pedonetomeo.archi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/avada_portfolio\/2076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/avada_portfolio"}],"about":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/types\/avada_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/avada_portfolio\/2076\/revisions"}],"predecessor-version":[{"id":2079,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/avada_portfolio\/2076\/revisions\/2079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/media\/2077"}],"wp:attachment":[{"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/media?parent=2076"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/portfolio_category?post=2076"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/portfolio_skills?post=2076"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/pedonetomeo.archi\/en\/wp-json\/wp\/v2\/portfolio_tags?post=2076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}